{"id":53788,"date":"2020-02-25T19:38:56","date_gmt":"2020-02-25T18:38:56","guid":{"rendered":"https:\/\/www.tamotor.se\/?post_type=product&#038;p=53788"},"modified":"2026-06-29T16:24:02","modified_gmt":"2026-06-29T14:24:02","slug":"avrinnings-slangar-innanfor-framruta","status":"publish","type":"product","link":"https:\/\/tamotor.se\/de\/produkt\/avrinnings-slangar-innanfor-framruta\/","title":{"rendered":"Ablaufschl\u00e4uche innerhalb der Windschutzscheibe"},"content":{"rendered":"<p>Ein Paar Ablaufschl\u00e4uche, die in der Windschutzscheibe sitzen. Rechts und links zwischen Armaturenbrett und Windschutzscheibe befindet sich ein kleiner ovaler Gummitrichter. Der Gummitrichter ist in einen 54 cm langen Schlauch einvulkanisiert und m\u00fcndet im vorderen Kotfl\u00fcgel. Je einer links und rechts. Dieses Set enth\u00e4lt ein Paar, das f\u00fcr ein Auto ben\u00f6tigt wird. Die kleinen Gummit\u00fcllen, an denen der Schlauch hinter dem Innenkotfl\u00fcgel m\u00fcndet, sind im Set enthalten. Auf den Bildern sehen Sie Beispiele f\u00fcr die \u00d6ffnungen der Schl\u00e4uche in den vorderen Kotfl\u00fcgeln.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ein Paar Ablaufschl\u00e4uche, die in der Windschutzscheibe sitzen. Sie finden rechts und links zwischen Armaturenbrett und Windschutzscheibe einen kleinen ovalen Gummitrichter. Der Gummitrichter ist in einen 54 cm langen Schlauch einvulkanisiert und endet im vorderen Kotfl\u00fcgel. Einer auf der linken und einer auf der rechten Seite. Dieses Set enth\u00e4lt ein Paar, das [\u2026]<\/p>","protected":false},"featured_media":53789,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"arsmodell":[7229,7230,7231,7232,7233,7234,7236],"product_cat":[7270],"product_tag":[],"class_list":{"0":"post-53788","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"supplier-7962","7":"arsmodell-7229","8":"arsmodell-7230","9":"arsmodell-7231","10":"arsmodell-7232","11":"arsmodell-7233","12":"arsmodell-7234","13":"arsmodell-7236","14":"product_cat-gummidetaljer","16":"first","17":"instock","18":"taxable","19":"shipping-taxable","20":"purchasable","21":"product-type-simple"},"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":6,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"acf":[],"_links":{"self":[{"href":"https:\/\/tamotor.se\/de\/wp-json\/wp\/v2\/product\/53788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamotor.se\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/tamotor.se\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamotor.se\/de\/wp-json\/wp\/v2\/media\/53789"}],"wp:attachment":[{"href":"https:\/\/tamotor.se\/de\/wp-json\/wp\/v2\/media?parent=53788"}],"wp:term":[{"taxonomy":"arsmodell","embeddable":true,"href":"https:\/\/tamotor.se\/de\/wp-json\/wp\/v2\/arsmodell?post=53788"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/tamotor.se\/de\/wp-json\/wp\/v2\/product_cat?post=53788"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/tamotor.se\/de\/wp-json\/wp\/v2\/product_tag?post=53788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}