{"id":9596,"date":"2025-11-13T13:17:51","date_gmt":"2025-11-13T12:17:51","guid":{"rendered":"http:\/\/www.tamotor.se\/?post_type=product&#038;p=9596"},"modified":"2026-07-07T15:14:49","modified_gmt":"2026-07-07T13:14:49","slug":"wstrip-ws-post-upper-to-door","status":"publish","type":"product","link":"https:\/\/tamotor.se\/de\/produkt\/wstrip-ws-post-upper-to-door\/","title":{"rendered":"Stehender Gummistreifen A-S\u00e4ule Windschutzscheibe"},"content":{"rendered":"<p>Dieser Gummistreifen wird am Windschutzscheibenpfosten montiert und dichtet gegen den Rahmen des L\u00fcftungsfensters ab. Auf Englisch hei\u00dft es \u201ePillar Post Seal\u201c, daher wird es bei uns in Schweden manchmal auch \u201ePillarpost List\u201c genannt. Wie auch immer wir es nennen, es ist sowohl f\u00fcr Windger\u00e4usche als auch f\u00fcr den Wasserabfluss sehr wichtig. Die L\u00e4nge betr\u00e4gt 38 cm und das Profil ist in der Originalversion aus bestem Gummimaterial gefertigt. Eine Charge enth\u00e4lt sowohl die rechte als auch die linke Seite. Es passt f\u00fcr alle zweit\u00fcrigen Autos, sowohl Coup\u00e9s als auch Fahrerh\u00e4user. Wenn Sie also ein 2-t\u00fcriges Auto haben, sind dies die richtigen Streifen f\u00fcr den A-Stoplen.<\/p>","protected":false},"excerpt":{"rendered":"<p>Diese Zierleiste passt f\u00fcr alle zweit\u00fcrigen Autos, sowohl Coup\u00e9s als auch Fahrerh\u00e4user.<\/p>","protected":false},"featured_media":27795,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"arsmodell":[7229,7230,7231],"product_cat":[7270],"product_tag":[],"class_list":{"0":"post-9596","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"supplier-7827","7":"arsmodell-7229","8":"arsmodell-7230","9":"arsmodell-7231","10":"product_cat-gummidetaljer","12":"first","13":"instock","14":"taxable","15":"shipping-taxable","16":"purchasable","17":"product-type-simple"},"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":3,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"acf":[],"_links":{"self":[{"href":"https:\/\/tamotor.se\/de\/wp-json\/wp\/v2\/product\/9596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tamotor.se\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/tamotor.se\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tamotor.se\/de\/wp-json\/wp\/v2\/media\/27795"}],"wp:attachment":[{"href":"https:\/\/tamotor.se\/de\/wp-json\/wp\/v2\/media?parent=9596"}],"wp:term":[{"taxonomy":"arsmodell","embeddable":true,"href":"https:\/\/tamotor.se\/de\/wp-json\/wp\/v2\/arsmodell?post=9596"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/tamotor.se\/de\/wp-json\/wp\/v2\/product_cat?post=9596"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/tamotor.se\/de\/wp-json\/wp\/v2\/product_tag?post=9596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}